{"id":28693,"date":"2025-07-16T16:45:53","date_gmt":"2025-07-16T15:45:53","guid":{"rendered":"https:\/\/www.coleggwent.ac.uk\/?p=28693&#038;post_type=course&#038;preview_id=28693"},"modified":"2026-02-15T12:14:44","modified_gmt":"2026-02-15T12:14:44","slug":"di0402","status":"publish","type":"course","link":"https:\/\/www.coleggwent.ac.uk\/cy\/course\/di0402\/eal-engineering-technologies-fabrication-and-welding-level-2","title":{"rendered":"EAL Diploma mewn Technolegau Peirianneg (Saern\u00efo a Weldio) Lefel 2"},"content":{"rendered":"<section class=\"masthead masthead-course bg-pink bg-pattern-accent bg-pattern-forward block-text-pos\">\n    <div class=\"masthead__inner inner\">\n        <div class=\"masthead__text bg-secondary fade-in\" data-course-id=\"28693\">\n            <ul class=\"masthead__tags tag-list list-unstyled\">\n                                <li>\n                    <span class=\"tag tag-uppercase accent-yellow\">\n                        Llawn Amser                    <\/span>\n                <\/li>\n                                                    <li>\n                        <span class=\"tag tag-uppercase level-2\">\n                            Lefel 2                        <\/span>\n                    <\/li>\n                            <\/ul>\n            <h1 class=\"display-3\">EAL Diploma mewn Technolegau Peirianneg (Saern\u00efo a Weldio) Lefel 2<\/h1>\n\n            <div class=\"js-add-to-favourites\">\n                <button class=\"btn btn-favourite\" aria-controls=\"offcanvasFavouriteCourses\" aria-label=\"Add to Favourite Courses\">\n                    <span class=\"material-symbols-outlined\">favorite<\/span>\n                    <span>Ychwanegu at fy ffefrynnau<\/span>\n                <\/button>\n            <\/div>\n\n\n            <div class=\"course-key-info__logo\">\n                            <\/div>\n        <\/div>\n\n            <\/div>\n    <div class=\"masthead__image shape-1\">\n                                    <picture>\n                    <source\n                        sizes=\"100vw\"\n                        srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-engineering-welding-alt-3.jpg 860w\"\n                        media=\"(max-width: 768px)\"\n                    >\n                    <source\n                        sizes=\"100vw\"\n                        srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-engineering-welding-alt-3.jpg 1210w\"\n                    >\n                    <img decoding=\"async\" src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-engineering-welding-alt-3.jpg\" alt=\"\">\n                <\/picture>\n                        <\/div>\n<\/section>\n\n\n\n    <a href=\"https:\/\/enrolment.coleggwent.ac.uk\/Page\/Prospectus_CourseOverview?uio_id=543547&#038;lang=cy\" class=\"btn btn-primary btn-fill\" target=\"_blank\">Ymgeisiwch nawr<\/a>\n\n\n<div class=\"course-key-info\">\n    <div class=\"course-key-info__container bg-secondary\">\n        <div class=\"course-key-info__inner inner\">\n            <div class=\"course-key-info__items\">\n                <dl class=\"course-key-info__details full-width-info\">\n                    <div class=\"course-key-info__col\">\n                        <dt>Maes Pwnc<\/dt>\n                        <dd>Peirianneg<\/dd>\n                    <\/div>\n\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Dyddiad Cychwyn<\/dt>\n                            <dd>\n                                                                    1 <span>Medi<\/span> 2026                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Hyd<\/dt>\n                            <dd>\n                                                                    1 <span>flwyddyn<\/span>                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Dull Astudio<\/dt>\n                            <dd>Llawn Amser<\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Lleoliad<\/dt>\n                            <dd><a href=\"#course-options\">Campws Dinas Casnewydd<\/a><\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Lefel<\/dt>\n                            <dd>2<\/dd>\n                        <\/div>\n                                    <\/dl>\n                \n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n<section class=\"course-text-content panel-m\">\n    <div class=\"course-text-content__inner inner\">\n        <div class=\"course-text-content__header section-header fade-in\">\n            <div class=\"row justify-content-center\">\n                <div class=\"col-lg-8 col-xl-6\">\n                    <h2 class=\"display-2 text-center\">Yn gryno<\/h2>\n                    <p class=\"lead text-center\">Bydd y cwrs hwn yn ymdrin ag amrywiaeth o unedau gorfodol a dewisol er mwyn datblygu eich sgiliau mewn technoleg saern\u00efo a weldio.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"course-text-content__accordions\">\n            <div class=\"row justify-content-center\">\n                <div class=\"col-lg-10 col-xl-8\">\n                    <div class=\"accordion\" id=\"accordionExample\">\n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingOne\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseOne\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseOne\">\n                                        Dyma'r cwrs i chi os...\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseOne\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingOne\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>...Mae gennych ddiddordeb mawr mewn saern\u00efo a weldio<\/p>\n<p>...Rydych chi'n gweithio'n dda yn annibynnol ac fel rhan o d\u00eem<\/p>\n<p>...Rydych chi'n greadigol ac yn weithgar<\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingTwo\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseTwo\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseTwo\">\n                                        Beth fyddaf yn ei wneud?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseTwo\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingTwo\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Byddwch yn dilyn amrywiaeth o unedau gorfodol a dewisol, yn cynnwys:<\/p>\n<ul>\n<li>Gweithio\u2019n ddiogel mewn amgylchedd peirianneg<\/li>\n<li>Egwyddorion technoleg beirianegol<\/li>\n<li>Egwyddorion saern\u00efo a weldio<\/li>\n<li>Prosesau weldio MMA i weldio deunyddiau<\/li>\n<li>Prosesau weldio MAGS i weldio deunyddiau<\/li>\n<li>Cynhyrchu cydosodiadau gwaith pl\u00e2t<\/li>\n<\/ul>\n<p>Byddwch yn meithrin sgiliau cyflogadwyedd hanfodol ac yn dysgu trwy gwblhau prosiectau ac aseiniadau\u2019n seiliedig ar sefyllfaoedd gweithle realistig.<\/p>\n<p>Byddwch yn cael eich asesu trwy gyfrwng arholiadau GOLA, gwaith cwrs, aseiniadau, gwaith portffolio, asesiadau labordy ac asesiadau ymarferol. Ar \u00f4l cwblhau\u2019r cwrs, byddwch yn ennill:<\/p>\n<ul type=\"disc\">\n<li>Diploma City &amp; Guilds Lefel 2 mewn Technoleg Beirianegol (Saern\u00efo a Weldio)<\/li>\n<li><a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/our-courses\/skills-development\">Gweithgareddau Sgiliau<\/a><\/li>\n<li><a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/our-courses\/improve-your-maths-and-english\">Mathemateg a Saesneg<\/a><\/li>\n<li>Cymwysterau perthnasol eraill i wella eich set sgiliau<\/li>\n<\/ul>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingFour\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseFour\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseFour\">\n                                        Beth sy'n digwydd nesaf?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseFour\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingFour\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Diploma City &amp; Guilds Lefel 3 mewn Technoleg Saern\u00efo a Weldio, a Phrentisiaeth addas neu waith fel technegydd saern\u00efo a weldio.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingFive\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseFive\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseFive\">\n                                        Gofynion mynediad\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseFive\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingFive\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <ul type=\"disc\">\n<li>4 TGAU gradd D neu uwch, yn cynnwys Mathemateg a Saesneg (neu Gymraeg Iaith Gyntaf) a Gwyddoniaeth; neu\nDiploma lefel 1 addas a TGAU gradd D neu uwch mewn Mathemateg a Saesneg (neu Gymraeg Iaith Gyntaf)<\/li>\n<li>4 TGAU gradd D neu uwch, yn cynnwys Mathemateg a Saesneg (neu Gymraeg Iaith Gyntaf) a Gwyddoniaeth; neu\nDiploma lefel 1 addas a TGAU gradd D neu uwch mewn Mathemateg a Saesneg (neu Gymraeg Iaith Gyntaf)<\/li>\n<\/ul>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<div class=\"feature-video bg-secondary\">\n    <div class=\"feature-video__image\">\n        <picture>\n            <source\n                sizes=\"100vw\"\n                srcset=\"                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Engineering-feature-video-mobile.jpg 860w\"\n                media=\"(max-width: 768px)\"\n            >\n            <source\n                sizes=\"100vw\"\n                srcset=\"                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Engineering-feature-video-desktop.jpg 1210w,                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Engineering-feature-video-desktop.jpg 1519w,                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Engineering-feature-video-desktop.jpg 3038w\"\n            >\n            <img decoding=\"async\" src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Engineering-feature-video-desktop.jpg\" alt=\"Engineering student smiling\">\n        <\/picture>\n    <\/div>\n    <div class=\"feature-video__modal-trigger\">\n        <button type=\"button\" class=\"btn btn-primary btn-play feature-video__button js-btn-play\" data-bs-toggle=\"modal\" data-bs-target=\"#videoModalFeatureVideo6415\">\n            <span class=\"sr-only\">Play Video<\/span>\n            <span class=\"material-symbols-outlined\">play_arrow<\/span>\n        <\/button>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"modal modal-video fade\" id=\"videoModalFeatureVideo6415\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"videoModalFeatureVideoLabel\" aria-hidden=\"true\">\n\n    <div class=\"modal-dialog modal-dialog-centered modal-xl\">\n        <div class=\"modal-content\">\n            <button type=\"button\" class=\"btn-close text-reset\" data-bs-dismiss=\"modal\" aria-label=\"Close\">\n                <span class=\"material-symbols-outlined\">close<\/span>\n            <\/button>\n            <div class=\"modal-body\">\n                <h2 class=\"sr-only\" id=\"videoModalFeatureVideoLabel\">modal video<\/h2>\n\n                <div class=\"ratio ratio-16x9\" data-video-src=\"https:\/\/www.youtube.com\/embed\/S_X81aEcZ1U?list=PLFNeewjoCG8oGfZc_VKHj_VUTwXU2fcXZ\"><\/div>\n\n            <\/div>\n\n\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n    <section class=\"course-options panel-p\" id=\"course-options\">\n                <div class=\"course-options__inner inner inner-hide-sm\">\n            <div class=\"course-options__items\">\n                <div class=\"row justify-content-center\">\n                    <div class=\"col-xl-10\">\n                                                    <div class=\"course-card-option fade-in\">\n                                <div class=\"course-card-option__inner\">\n                                    <div class=\"course-card-option__content\">\n                                        <h3 class=\"course-card-option__title h2\">Campws Dinas Casnewydd<\/h3>\n                                        <dl class=\"course-card-option__details\">\n                                            <div class=\"course-card-option__col\">\n                                                <dt>C\u00f4d y Cwrs<\/dt>\n                                                <dd>NFDI0402AA<\/dd>\n                                            <\/div>\n                                                                                                                                        <div class=\"course-card-option__col\">\n                                                    <dt>Hyd<\/dt>\n                                                    <dd>1 <span>flwyddyn<\/span><\/dd>\n                                                <\/div>\n                                                                                                                                                                                    <div class=\"course-card-option__col\">\n                                                    <dt>Dull Astudio<\/dt>\n                                                    <dd>Llawn Amser<\/dd>\n                                                <\/div>\n                                                                                                                                <\/dl>\n                                                                            <\/div>\n\n                                    <div class=\"course-card-option__buttons\">\n                                        \n                                                                                    <a href=\"https:\/\/enrolment.coleggwent.ac.uk\/Page\/Prospectus_CourseOverview?uio_id=543547&#038;lang=cy\" class=\"btn btn-primary\" target=\"_blank\">\n                                                                                                    <span class=\"apply-day\">1<\/span>\n                                                    <span class=\"apply-month\">Medi <\/span>\n                                                    <span class=\"apply-year\">2026<\/span>\n                                                    <span class=\"apply-separator\">&#8211;<\/span>\n                                                    <span class=\"apply-cta\">Ymgeisiwch nawr<\/span>\n                                                                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                    <div class=\"course-card-option__inner course-card-option__disclaimer inner\">\n                <div class=\"row\">\n                    <div class=\"col-xl-1\"><\/div>\n                    <div class=\"col-xl-10\">\n                        \n                                                    <p>Gall yr holl gyrsiau fod yn agored i newid a\u2019u canslo os tybir nad yw\u2019n bosib eu cynnal.<\/p>\n                                            <\/div>\n                    <div class=\"col-xl-1\"><\/div>\n                <\/div>\n            <\/div>\n            <\/section>\n\n\n\n<section class=\"container\">\n    <div class=\"inner\">\n                    <div id=\"pathways-d6b53d\" data-subject=\"automap\" data-callback=\"loadCallback\" data-lang=\"cy\"><\/div>\n            <script src=\"https:\/\/www.career-pathways.co.uk\/assets\/js\/pathways-loader.js\" data-key=\"c8daae74df1eb436ee1072e63d20e706\" async crossorigin=\"anonymous\"><\/script>\n                <script>\n            function loadCallback(iframeId, message) {\n                if (message === 'No automapped subject found') {\n                    iframeId.style.display = 'none';\n                    \n                                    }\n            }\n        <\/script>\n    <\/div>\n<\/section>\n\n\n\n\n\n\n\n\n\n\n<section class=\"related-courses panel-m\">\n            <div class=\"related-courses__inner inner\">\n            <h2 class=\"block-title h3 fade-in\">Cyrsiau a all fod at eich dant<\/h2>\n        <\/div>\n        <div class=\"related-courses__inner inner inner-hide-sm\">\n        <div class=\"related-courses__items\">\n            <div class=\"row\">\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-2\">\n                                                Lefel 2                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/dh0402\/eal-engineering-technologies-mechanical-level-2\" class=\"related-course-card__title h2\">EAL Diploma mewn Technolegau Peirianneg (Mecanyddol) Lefel 2<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-2\">\n                                                Lefel 2                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/di0463\/city-guilds-diploma-in-engineering-electrical-and-electronic-technology-level-2\" class=\"related-course-card__title h2\">City &amp; Guilds Diploma mewn Peirianneg (Technoleg Drydanol ac Electronig) Lefel 2<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-2\">\n                                                Lefel 2                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/di0401\/city-guilds-diploma-in-engineering-mechanical-level-2\" class=\"related-course-card__title h2\">City &amp; Guilds Diploma mewn Peirianneg (Mecanyddol) Lefel 2<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n            <div class=\"related-courses__inner inner\">\n                        <a href=\"\/cy\/course-search\" class=\"btn btn-primary\">Gweld pob cwrs<\/a>\n        <\/div>\n    <\/section>\n\n\n\n<section class=\"latest-events position-relative overflow-hidden panel-m\">\n    <div class=\"latest-events__inner inner\">\n        <div class=\"latest-events__header swiper-navigation-header\">\n                            <h2 class=\"block-title h3 fade-in\">Digwyddiadau i ddod<\/h2>\n            \n            <div class=\"latest-events__navigation swiper-navigation swiper-primary\">\n                <button class=\"swiper-button-prev\">\n                    <span class=\"material-symbols-outlined\">chevron_left<\/span>\n                <\/button>\n                <button class=\"swiper-button-next\">\n                    <span class=\"material-symbols-outlined\">chevron_right<\/span>\n                <\/button>\n            <\/div>\n        <\/div>\n        <div class=\"latest-events__items fade-in-cards js-latest-events\">\n            <div class=\"swiper-wrapper\">\n                                                                <div class=\"swiper-slide fade-in\">\n                            <div class=\"card-event accent-yellow\">\n                                <div class=\"card-event__inner\">\n                                                                            <div class=\"card-event__image\">\n\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/event-thumb-5.jpg\" class=\"attachment-full size-full\" alt=\"Students smiling outside campus\" srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/event-thumb-5.jpg 800w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/event-thumb-5-300x225.jpg 300w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/event-thumb-5-768x576.jpg 768w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/event-thumb-5-16x12.jpg 16w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/event-thumb-5-373x280.jpg 373w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>                                        <\/div>\n                                                                        <div class=\"card-event__content\">\n                                                                                    <time class=\"card-event__date display-6\" datetime=\"2026-06-23\">\n                                                <span>\n                                                    Meh                                                <\/span>\n                                                <span>\n                                                    23                                                <\/span>\n                                            <\/time>\n                                                                                <div class=\"card-event__text\">\n                                            <h3 class=\"card-event__title h2\">\n                                                Noson Agored Coleg Mehefin 2026                                            <\/h3>\n                                            <dl class=\"card-event__details\">\n                                                                                                    <div>\n                                                        <dt>Manylion<\/dt>\n                                                        <dd>Pob cwrs<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Lleoliad<\/dt>\n                                                        <dd>Pob campws<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Amser<\/dt>\n                                                        <dd>5yp - 7.30yp<\/dd>\n                                                    <\/div>\n                                                                                            <\/dl>\n                                                                                            <a href=\"https:\/\/www.eventbrite.com\/cc\/digwyddiad-agored-coleg-gwent-23-mehefin-2026-4828255\" class=\"btn btn-primary\" aria-label=\"Register for the June 2026 College Open Evening\" target=\"_blank\">\n                                                    Ymgeisiwch nawr                                                <\/a>\n                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                                                <div class=\"swiper-slide fade-in\">\n                            <div class=\"card-event accent-yellow\">\n                                <div class=\"card-event__inner\">\n                                                                            <div class=\"card-event__image\">\n\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb.jpg\" class=\"attachment-full size-full\" alt=\"Higher Education students walking with tutor\" srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb.jpg 800w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-300x225.jpg 300w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-768x576.jpg 768w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-16x12.jpg 16w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-373x280.jpg 373w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>                                        <\/div>\n                                                                        <div class=\"card-event__content\">\n                                                                                    <time class=\"card-event__date display-6\" datetime=\"2026-08-19\">\n                                                <span>\n                                                    Aws                                                <\/span>\n                                                <span>\n                                                    19                                                <\/span>\n                                            <\/time>\n                                                                                <div class=\"card-event__text\">\n                                            <h3 class=\"card-event__title h2\">\n                                                Digwyddiad Agored Addysg Uwch Awst 2026                                            <\/h3>\n                                            <dl class=\"card-event__details\">\n                                                                                                    <div>\n                                                        <dt>Manylion<\/dt>\n                                                        <dd>Higher education courses<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Lleoliad<\/dt>\n                                                        <dd>I\u2019w gadarnhau<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Amser<\/dt>\n                                                        <dd>3yp - 6yp<\/dd>\n                                                    <\/div>\n                                                                                            <\/dl>\n                                                                                            <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/open-events\" class=\"btn btn-primary\" aria-label=\"Register for the August 2026 Higher Education Open Event\">\n                                                    Darganfod mwy                                                <\/a>\n                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"cta-button-group panel-m flip\">\n    <div class=\"cta-button-group__inner inner\">\n        <div class=\"cta-button-group__content bg-pink bg-pattern-accent\">\n            <div class=\"cta-button-group__image shape-2\">\n                                    <picture>\n                        <source\n                            sizes=\"100vw\"\n                            srcset=\" https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-engineering-welding-alt-3.jpg 860w\"\n                            media=\"(max-width: 768px)\"\n                                >\n                        <source\n                            sizes=\"(min-width: 1512px) 100vw, 1366px\"\n                            srcset=\"                                https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-engineering-welding-alt-3.jpg 1366w\"\n                                >\n                        <img decoding=\"async\" src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-engineering-welding-alt-3.jpg\" alt=\"\">\n                    <\/picture>\n                            <\/div>\n            <div class=\"cta-button-group__text fade-in\">\n                <div class=\"cta-button-group__title\">\n                    <div class=\"block-text accent-pink\">\n                        <div class=\"block-text__body\">\n                                                            <h2 class=\"display-2\">\n                                    <strong>Oes diddordeb gennych chi?\n<\/strong>\n                                <\/h2>\n                                                                                <\/div>\n                    <\/div>\n                <\/div>\n                <ul class=\"block-list cta-button-group__list-wrapper list-unstyled\">\n                                                                                                                                    <li>\n                                    <a href=\"#course-options\">Ymgeisiwch<\/a>\n                                <\/li>\n                                                                                                                                            <li>\n                                    <a href=\"\/cy\/contact\/?enquiry_type=course_enquiry#form\">Holi<\/a>\n                                <\/li>\n                                                                                                                                            <li>\n                                    <a href=\"mailto:helo@coleggwent.ac.uk\">Cysylltwch \u00e2\u2019n t\u00eem recriwtio myfyrwyr<\/a>\n                                <\/li>\n                                                                                        <\/ul>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":29212,"template":"","subject":[39,87],"course-type":[122],"locations":[118],"sector":[],"promotions":[],"class_list":["post-28693","course","type-course","status-publish","has-post-thumbnail","hentry","subject-engineering","subject-fabrication-and-welding","course-type-full-time","locations-city-of-newport-campus"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","pp_post_mime_type":"","acf":[],"_links":{"self":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/types\/course"}],"author":[{"embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/users\/14"}],"version-history":[{"count":5,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28693\/revisions"}],"predecessor-version":[{"id":35682,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28693\/revisions\/35682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/media\/29212"}],"wp:attachment":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/media?parent=28693"}],"wp:term":[{"taxonomy":"subject","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/subject?post=28693"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course-type?post=28693"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/locations?post=28693"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/sector?post=28693"},{"taxonomy":"promotions","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/promotions?post=28693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}