{"id":28667,"date":"2025-07-16T16:48:24","date_gmt":"2025-07-16T15:48:24","guid":{"rendered":"https:\/\/www.coleggwent.ac.uk\/?p=28667&#038;post_type=course&#038;preview_id=28667"},"modified":"2026-02-15T12:14:44","modified_gmt":"2026-02-15T12:14:44","slug":"bd0001","status":"publish","type":"course","link":"https:\/\/www.coleggwent.ac.uk\/cy\/course\/bd0001\/ocr-cambridge-technical-diploma-in-art-and-design-level-2","title":{"rendered":"OCR Diploma Technegol Caergrawnt mewn Celf a Dylunio Lefel 2"},"content":{"rendered":"<section class=\"masthead masthead-course bg-pink bg-pattern-accent bg-pattern-forward block-text-pos\">\n    <div class=\"masthead__inner inner\">\n        <div class=\"masthead__text bg-secondary fade-in\" data-course-id=\"28667\">\n            <ul class=\"masthead__tags tag-list list-unstyled\">\n                                <li>\n                    <span class=\"tag tag-uppercase accent-yellow\">\n                        Llawn Amser                    <\/span>\n                <\/li>\n                                                    <li>\n                        <span class=\"tag tag-uppercase level-2\">\n                            Lefel 2                        <\/span>\n                    <\/li>\n                            <\/ul>\n            <h1 class=\"display-3\">OCR Diploma Technegol Caergrawnt mewn Celf a Dylunio Lefel 2<\/h1>\n\n            <div class=\"js-add-to-favourites\">\n                <button class=\"btn btn-favourite\" aria-controls=\"offcanvasFavouriteCourses\" aria-label=\"Add to Favourite Courses\">\n                    <span class=\"material-symbols-outlined\">favorite<\/span>\n                    <span>Ychwanegu at fy ffefrynnau<\/span>\n                <\/button>\n            <\/div>\n\n\n            <div class=\"course-key-info__logo\">\n                            <\/div>\n        <\/div>\n\n            <\/div>\n    <div class=\"masthead__image shape-1\">\n                                    <picture>\n                    <source\n                        data-sizes=\"100vw\"\n                        data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-art-design-class-10.jpg 860w\"\n                        media=\"(max-width: 768px)\"\n                    >\n                    <source\n                        data-sizes=\"100vw\"\n                        data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-art-design-class-10.jpg 1210w\"\n                    >\n                    <img decoding=\"async\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-art-design-class-10.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1185px; --smush-placeholder-aspect-ratio: 1185\/474;\">\n                <\/picture>\n                        <\/div>\n<\/section>\n\n\n\n    <a href=\"https:\/\/enrolment.coleggwent.ac.uk\/Page\/Prospectus_CourseOverview?uio_id=544007&#038;lang=cy\" class=\"btn btn-primary btn-fill\" target=\"_blank\">Ymgeisiwch nawr<\/a>\n\n\n<div class=\"course-key-info\">\n    <div class=\"course-key-info__container bg-secondary\">\n        <div class=\"course-key-info__inner inner\">\n            <div class=\"course-key-info__items\">\n                <dl class=\"course-key-info__details full-width-info\">\n                    <div class=\"course-key-info__col\">\n                        <dt>Maes Pwnc<\/dt>\n                        <dd>Celf, Cyfryngau, Dylunio a Ffotograffiaeth<\/dd>\n                    <\/div>\n\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Dyddiad Cychwyn<\/dt>\n                            <dd>\n                                                                    2 <span>Medi<\/span> 2026                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Hyd<\/dt>\n                            <dd>\n                                                                    1 <span>flwyddyn<\/span>                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Dull Astudio<\/dt>\n                            <dd>\n                                                                    Llawn Amser                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Lleoliad<\/dt>\n                            <dd><a href=\"#course-options\">Campws Dinas Casnewydd<\/a><\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Lefel<\/dt>\n                            <dd>2<\/dd>\n                        <\/div>\n                                    <\/dl>\n                \n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n<section class=\"course-text-content panel-m\">\n    <div class=\"course-text-content__inner inner\">\n        <div class=\"course-text-content__header section-header fade-in\">\n            <div class=\"row justify-content-center\">\n                <div class=\"col-lg-8 col-xl-6\">\n                    <h2 class=\"display-2 text-center\">Yn gryno<\/h2>\n                    <p class=\"lead text-center\">Byddwch chi\u2019n astudio ystod eang o unedau, megis gwneud printiau, serameg, cyfrifiaduron, delweddu digidol, ffotograffiaeth, astudiaethau gweledol, ffasiwn a thecstilau, astudiaethau hanesyddol a chyd-destunol, darlunio, arlunio, dylunio 3D a dylunio graffeg.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"course-text-content__accordions\">\n            <div class=\"row justify-content-center\">\n                <div class=\"col-lg-10 col-xl-8\">\n                    <div class=\"accordion\" id=\"accordionExample\">\n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingOne\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseOne\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseOne\">\n                                        Dyma'r cwrs i chi os...\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseOne\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingOne\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>... Ydych eisiau adeiladu sgiliau a hyder mewn ystod o ddisgyblaethau<\/p>\n<p>... Rydych chi\u2019n dymuno dilyn gyrfa ym meysydd celf a dylunio.<\/p>\n<p>... Oes gennych ychydig o brofiad ym maes celf ond hoffech ei archwilio fwy<\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingTwo\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseTwo\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseTwo\">\n                                        Beth fyddaf yn ei wneud?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseTwo\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingTwo\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Mae\u2019r cwrs hwn yn ddelfrydol os oes gennych chi ddiddordeb mewn datblygu sgiliau a magu hyder ar draws ystod o ddisgyblaethau gan obeithio dilyn gyrfa ym maes celf a dylunio yn nes ymlaen. Os oes eisoes gennych chi rywfaint o brofiad ond nid ydych wedi cael cyfle i archwilio eich ochr greadigol yn llawn, bydd y cwrs hwn yn eich helpu chi i wneud hynny. Mae\u2019n rhagflas go iawn ar nifer o agweddau ar gelf a dylunio ac mae\u2019n cynnwys prosiectau cyffrous a heriol.\n\nByddwch chi hefyd yn datblygu sgiliau ym meysydd cyfathrebu, technoleg gwybodaeth, defnyddio rhifau, cynllunio a gwaith t\u00eem.\n\nCewch eich asesu drwy waith cwrs sy\u2019n seiliedig ar dasgau ymarferol a chaiff eich gwaith ei gymedroli\u2019n allanol. Ar \u00f4l cwblhau\u2019r cwrs, byddwch chi\u2019n ennill:\n\nCymhwyster Lefel 2 mewn Celf a Dylunio\nGweithgareddau Sgiliau\nMathemateg a Saesneg\nCymwysterau perthnasol eraill i wella eich set sgiliau<\/p>\n<p>Byddwch chi hefyd yn datblygu sgiliau ym meysydd cyfathrebu, technoleg gwybodaeth, defnyddio rhifau, cynllunio a gwaith t\u00eem.<\/p>\n<p>Cewch eich asesu drwy waith cwrs sy\u2019n seiliedig ar dasgau ymarferol a chaiff eich gwaith ei gymedroli\u2019n allanol. Ar \u00f4l cwblhau\u2019r cwrs, byddwch chi\u2019n ennill:<\/p>\n<ul type=\"disc\">\n<li>Lefel 2 mewn Celf a Dylunio<\/li>\n<li><a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/our-courses\/skills-development\">Gweithgareddau Sgiliau<\/a><\/li>\n<li><a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/our-courses\/improve-your-maths-and-english\">Mathemateg a Saesneg<\/a><\/li>\n<li>Cymwysterau perthnasol eraill i wella eich set sgiliau<\/li>\n<\/ul>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingThree\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseThree\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseThree\">\n                                        Beth a ddisgwylir ohonof i?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseThree\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingThree\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Mae ymroddiad llwyr i bresenoldeb yn ofynnol, ynghyd \u00e2 pharch at eraill, brwdfrydedd dros y pwnc, hunanysgogiad, gallu creadigol ac awydd i lwyddo.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingFour\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseFour\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseFour\">\n                                        Beth sy'n digwydd nesaf?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseFour\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingFour\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Diploma Lefel 3 mewn Celf a Dylunio a\u2019r Cyfryngau Rhyngweithiol.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingFive\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseFive\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseFive\">\n                                        Gofynion mynediad\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseFive\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingFive\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>O leiaf 4 cymhwyster TGAU, gradd D neu uwch, gan gynnwys Celf neu bwnc creadigol cysylltiedig a, naill ai Mathemateg\/Rhifedd neu Saesneg\/Cymraeg Iaith Gyntaf; neu gymhwyster Diploma Lefel 1 perthnasol yn y maes galwedigaethol priodol gan gynnwys naill ai TGAU Mathemateg\/Rhifedd neu Saesneg\/Cymraeg Iaith Gyntaf.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingSix\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseSix\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseSix\">\n                                        Gwybodaeth ychwanegol\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseSix\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingSix\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Bydd angen i chi brynu llyfrau braslunio, deunyddiau peintio ac arlunio. Efallai y bydd angen talu ffioedd ar gyfer ymweliadau \u00e2\u2019r oriel a digwyddiadau a gynhelir drwy gydol y flwyddyn.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<div class=\"feature-video bg-secondary\">\n    <div class=\"feature-video__image\">\n        <picture>\n            <source\n                data-sizes=\"100vw\"\n                data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/10\/Art-and-Design-feature-video-mobile.jpg 860w\"\n                media=\"(max-width: 768px)\"\n            >\n            <source\n                data-sizes=\"100vw\"\n                data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/10\/Art-and-Design-feature-video-desktop.jpg 1210w,                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/10\/Art-and-Design-feature-video-desktop.jpg 1519w,                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/10\/Art-and-Design-feature-video-desktop.jpg 3038w\"\n            >\n            <img decoding=\"async\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/10\/Art-and-Design-feature-video-desktop.jpg\" alt=\"Art-and-Design\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 3024px; --smush-placeholder-aspect-ratio: 3024\/1400;\">\n        <\/picture>\n    <\/div>\n    <div class=\"feature-video__modal-trigger\">\n        <button type=\"button\" class=\"btn btn-primary btn-play feature-video__button js-btn-play\" data-bs-toggle=\"modal\" data-bs-target=\"#videoModalFeatureVideo8465\">\n            <span class=\"sr-only\">Play Video<\/span>\n            <span class=\"material-symbols-outlined\">play_arrow<\/span>\n        <\/button>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"modal modal-video fade\" id=\"videoModalFeatureVideo8465\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"videoModalFeatureVideoLabel\" aria-hidden=\"true\">\n\n    <div class=\"modal-dialog modal-dialog-centered modal-xl\">\n        <div class=\"modal-content\">\n            <button type=\"button\" class=\"btn-close text-reset\" data-bs-dismiss=\"modal\" aria-label=\"Close\">\n                <span class=\"material-symbols-outlined\">close<\/span>\n            <\/button>\n            <div class=\"modal-body\">\n                <h2 class=\"sr-only\" id=\"videoModalFeatureVideoLabel\">modal video<\/h2>\n\n                <div class=\"ratio ratio-16x9\" data-video-src=\"https:\/\/www.youtube.com\/embed\/QNd9n1UgJzA?list=PLFNeewjoCG8oGfZc_VKHj_VUTwXU2fcXZ&amp;cc_load_policy=0\"><\/div>\n\n            <\/div>\n\n\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n    <section class=\"course-options panel-p\" id=\"course-options\">\n                <div class=\"course-options__inner inner inner-hide-sm\">\n            <div class=\"course-options__items\">\n                <div class=\"row justify-content-center\">\n                    <div class=\"col-xl-10\">\n                                                    <div class=\"course-card-option fade-in\">\n                                <div class=\"course-card-option__inner\">\n                                    <div class=\"course-card-option__content\">\n                                        <h3 class=\"course-card-option__title h2\">Campws Dinas Casnewydd<\/h3>\n                                        <dl class=\"course-card-option__details\">\n                                            <div class=\"course-card-option__col\">\n                                                <dt>C\u00f4d y Cwrs<\/dt>\n                                                <dd>NFBD0063AA<\/dd>\n                                            <\/div>\n                                                                                            <div class=\"course-card-option__col\">\n                                                    <dt>Dull Astudio<\/dt>\n                                                    <dd>Llawn Amser<\/dd>\n                                                <\/div>\n                                                                                                                                        <div class=\"course-card-option__col\">\n                                                    <dt>Hyd<\/dt>\n                                                    <dd>1 <span>flwyddyn<\/span><\/dd>\n                                                <\/div>\n                                                                                                                                                                                                                                                                    <\/dl>\n                                                                            <\/div>\n\n                                    <div class=\"course-card-option__buttons\">\n                                        \n                                                                                    <a href=\"https:\/\/enrolment.coleggwent.ac.uk\/Page\/Prospectus_CourseOverview?uio_id=544007&#038;lang=cy\" class=\"btn btn-primary\" target=\"_blank\">\n                                                                                                    <span class=\"apply-day\">2<\/span>\n                                                    <span class=\"apply-month\">Medi <\/span>\n                                                    <span class=\"apply-year\">2026<\/span>\n                                                    <span class=\"apply-separator\">&#8211;<\/span>\n                                                    <span class=\"apply-cta\">Ymgeisiwch nawr<\/span>\n                                                                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                    <div class=\"course-card-option__inner course-card-option__disclaimer inner\">\n                <div class=\"row\">\n                    <div class=\"col-xl-1\"><\/div>\n                    <div class=\"col-xl-10\">\n                        \n                                                    <p>Gall yr holl gyrsiau fod yn agored i newid a\u2019u canslo os tybir nad yw\u2019n bosib eu cynnal.<\/p>\n                                            <\/div>\n                    <div class=\"col-xl-1\"><\/div>\n                <\/div>\n            <\/div>\n            <\/section>\n\n\n\n<section class=\"container\">\n    <div class=\"inner\">\n                    <div id=\"pathways-d6b53d\" data-subject=\"automap\" data-callback=\"loadCallback\" data-lang=\"cy\"><\/div>\n            <script src=\"https:\/\/www.career-pathways.co.uk\/assets\/js\/pathways-loader.js\" data-key=\"c8daae74df1eb436ee1072e63d20e706\" async crossorigin=\"anonymous\"><\/script>\n                <script>\n            function loadCallback(iframeId, message) {\n                if (message === 'No automapped subject found') {\n                    iframeId.style.display = 'none';\n                    \n                                    }\n            }\n        <\/script>\n    <\/div>\n<\/section>\n\n\n\n\n\n\n\n\n\n\n<section class=\"related-courses panel-m\">\n            <div class=\"related-courses__inner inner\">\n            <h2 class=\"block-title h3 fade-in\">Cyrsiau a all fod at eich dant<\/h2>\n        <\/div>\n        <div class=\"related-courses__inner inner inner-hide-sm\">\n        <div class=\"related-courses__items\">\n            <div class=\"row\">\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-3\">\n                                                Lefel 3                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/be0036\/btec-diploma-in-creative-media-production-level-3\" class=\"related-course-card__title h2\">BTEC Diploma Cenedlaethol mewn Cynhyrchu Cyfryngau Creadigol Lefel 3<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-1\">\n                                                Lefel 1                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/bg0047\/btec-diploma-in-vocational-studies-art-and-creative-media-level-1\" class=\"related-course-card__title h2\">BTEC Diploma mewn Astudiaethau Galwedigaethol \u2013 Celf a'r Cyfryngau Creadigol Lefel 1<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-2\">\n                                                Lefel 2                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/dh0671\/ual-diploma-in-creative-media-production-technology-media-photography-level-2\" class=\"related-course-card__title h2\">UAL Diploma mewn Cynhyrchu a Thechnoleg y Cyfryngau Creadigol (Cyfryngau a Ffotograffiaeth) Lefel 2<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n            <div class=\"related-courses__inner inner\">\n                        <a href=\"\/cy\/course-search\" class=\"btn btn-primary\">Gweld pob cwrs<\/a>\n        <\/div>\n    <\/section>\n\n\n\n<section class=\"latest-events position-relative overflow-hidden panel-m\">\n    <div class=\"latest-events__inner inner\">\n        <div class=\"latest-events__header swiper-navigation-header\">\n                            <h2 class=\"block-title h3 fade-in\">Digwyddiadau i ddod<\/h2>\n            \n            <div class=\"latest-events__navigation swiper-navigation swiper-primary\">\n                <button class=\"swiper-button-prev\">\n                    <span class=\"material-symbols-outlined\">chevron_left<\/span>\n                <\/button>\n                <button class=\"swiper-button-next\">\n                    <span class=\"material-symbols-outlined\">chevron_right<\/span>\n                <\/button>\n            <\/div>\n        <\/div>\n        <div class=\"latest-events__items fade-in-cards js-latest-events\">\n            <div class=\"swiper-wrapper\">\n                                                                <div class=\"swiper-slide fade-in\">\n                            <div class=\"card-event accent-yellow\">\n                                <div class=\"card-event__inner\">\n                                                                            <div class=\"card-event__image\">\n\n                                            <img decoding=\"async\" width=\"800\" height=\"600\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb.jpg\" class=\"attachment-full size-full lazyload\" alt=\"Higher Education students walking with tutor\" data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb.jpg 800w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-300x225.jpg 300w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-768x576.jpg 768w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-16x12.jpg 16w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-373x280.jpg 373w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/600;\" \/>                                        <\/div>\n                                                                        <div class=\"card-event__content\">\n                                                                                    <time class=\"card-event__date display-6\" datetime=\"2026-08-19\">\n                                                <span>\n                                                    Aws                                                <\/span>\n                                                <span>\n                                                    19                                                <\/span>\n                                            <\/time>\n                                                                                <div class=\"card-event__text\">\n                                            <h3 class=\"card-event__title h2\">\n                                                Digwyddiad Agored Addysg Uwch Awst 2026                                            <\/h3>\n                                            <dl class=\"card-event__details\">\n                                                                                                    <div>\n                                                        <dt>Manylion<\/dt>\n                                                        <dd>Cyrsiau addysg uwch<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Lleoliad<\/dt>\n                                                        <dd>Parth Dysgu Blaenau Gwent - Glynebwy<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Amser<\/dt>\n                                                        <dd>2yp - 5yp<\/dd>\n                                                    <\/div>\n                                                                                            <\/dl>\n                                                                                            <a href=\"https:\/\/www.eventbrite.co.uk\/e\/digwyddiad-agored-coleg-gwent-addysg-uwch-tickets-1992480197908\" class=\"btn btn-primary\" aria-label=\"Register for the August 2026 Higher Education Open Event\" target=\"_blank\">\n                                                    Ymgeisiwch nawr                                                <\/a>\n                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"cta-button-group panel-m flip\">\n    <div class=\"cta-button-group__inner inner\">\n        <div class=\"cta-button-group__content bg-pink bg-pattern-accent\">\n            <div class=\"cta-button-group__image shape-2\">\n                                    <picture>\n                        <source\n                            data-sizes=\"100vw\"\n                            data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-art-design-class-10.jpg 860w\"\n                            media=\"(max-width: 768px)\"\n                                >\n                        <source\n                            data-sizes=\"(min-width: 1512px) 100vw, 1366px\"\n                            data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-art-design-class-10.jpg 1366w\"\n                                >\n                        <img decoding=\"async\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-art-design-class-10.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1185px; --smush-placeholder-aspect-ratio: 1185\/474;\">\n                    <\/picture>\n                            <\/div>\n            <div class=\"cta-button-group__text fade-in\">\n                <div class=\"cta-button-group__title\">\n                    <div class=\"block-text accent-pink\">\n                        <div class=\"block-text__body\">\n                                                            <h2 class=\"display-2\">\n                                    <strong>Oes diddordeb gennych chi?\n<\/strong>\n                                <\/h2>\n                                                                                <\/div>\n                    <\/div>\n                <\/div>\n                <ul class=\"block-list cta-button-group__list-wrapper list-unstyled\">\n                                                                                                                                    <li>\n                                    <a href=\"#course-options\">Ymgeisiwch<\/a>\n                                <\/li>\n                                                                                                                                            <li>\n                                    <a href=\"\/cy\/contact\/?enquiry_type=course_enquiry#form\">Holi<\/a>\n                                <\/li>\n                                                                                                                                            <li>\n                                    <a href=\"mailto:helo@coleggwent.ac.uk\">Cysylltwch \u00e2\u2019n t\u00eem recriwtio myfyrwyr<\/a>\n                                <\/li>\n                                                                                        <\/ul>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":18,"featured_media":29456,"template":"","subject":[154,58],"course-type":[122],"locations":[118],"sector":[],"promotions":[],"class_list":["post-28667","course","type-course","status-publish","has-post-thumbnail","hentry","course-type-full-time","locations-city-of-newport-campus"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","pp_force_visibility":null,"pp_subpost_visibility":null,"pp_inherited_force_visibility":null,"pp_inherited_subpost_visibility":null,"pp_post_mime_type":"","acf":[],"_links":{"self":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/types\/course"}],"author":[{"embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/users\/18"}],"version-history":[{"count":5,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28667\/revisions"}],"predecessor-version":[{"id":35975,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28667\/revisions\/35975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/media\/29456"}],"wp:attachment":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/media?parent=28667"}],"wp:term":[{"taxonomy":"subject","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/subject?post=28667"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course-type?post=28667"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/locations?post=28667"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/sector?post=28667"},{"taxonomy":"promotions","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/promotions?post=28667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}