{"id":28516,"date":"2025-07-16T16:49:30","date_gmt":"2025-07-16T15:49:30","guid":{"rendered":"https:\/\/www.coleggwent.ac.uk\/?p=28516&#038;post_type=course&#038;preview_id=28516"},"modified":"2026-02-15T12:14:44","modified_gmt":"2026-02-15T12:14:44","slug":"br0006","status":"publish","type":"course","link":"https:\/\/www.coleggwent.ac.uk\/cy\/course\/br0006\/rsl-subsidiary-diploma-for-music-practitioners-level-3","title":{"rendered":"RSL Diploma Atodol i Ymarferwyr Cerddoriaeth Lefel 3"},"content":{"rendered":"<section class=\"masthead masthead-course bg-pink bg-pattern-accent bg-pattern-forward block-text-pos\">\n    <div class=\"masthead__inner inner\">\n        <div class=\"masthead__text bg-secondary fade-in\" data-course-id=\"28516\">\n            <ul class=\"masthead__tags tag-list list-unstyled\">\n                                <li>\n                    <span class=\"tag tag-uppercase accent-yellow\">\n                        Llawn Amser                    <\/span>\n                <\/li>\n                                                    <li>\n                        <span class=\"tag tag-uppercase level-3\">\n                            Lefel 3                        <\/span>\n                    <\/li>\n                            <\/ul>\n            <h1 class=\"display-3\">RSL Diploma Atodol i Ymarferwyr Cerddoriaeth Lefel 3<\/h1>\n\n            <div class=\"js-add-to-favourites\">\n                <button class=\"btn btn-favourite\" aria-controls=\"offcanvasFavouriteCourses\" aria-label=\"Add to Favourite Courses\">\n                    <span class=\"material-symbols-outlined\">favorite<\/span>\n                    <span>Ychwanegu at fy ffefrynnau<\/span>\n                <\/button>\n            <\/div>\n\n\n            <div class=\"course-key-info__logo\">\n                            <\/div>\n        <\/div>\n\n            <\/div>\n    <div class=\"masthead__image shape-1\">\n                                    <picture>\n                    <source\n                        data-sizes=\"100vw\"\n                        data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-music-performance-3.jpg 860w\"\n                        media=\"(max-width: 768px)\"\n                    >\n                    <source\n                        data-sizes=\"100vw\"\n                        data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-music-performance-3.jpg 1210w\"\n                    >\n                    <img decoding=\"async\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-music-performance-3.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1185px; --smush-placeholder-aspect-ratio: 1185\/474;\">\n                <\/picture>\n                        <\/div>\n<\/section>\n\n    <a href=\"https:\/\/enrolment.coleggwent.ac.uk\/Page\/Prospectus_CourseOverview?uio_id=542890&#038;lang=cy\" class=\"btn btn-primary btn-fill\" target=\"_blank\">Ymgeisiwch nawr<\/a>\n<div class=\"course-key-info\">\n    <div class=\"course-key-info__container bg-secondary\">\n        <div class=\"course-key-info__inner inner\">\n            <div class=\"course-key-info__items\">\n                <dl class=\"course-key-info__details full-width-info\">\n                    <div class=\"course-key-info__col\">\n                        <dt>Maes Pwnc<\/dt>\n                        <dd>Cerddoriaeth a Chelfyddydau Perfformio<\/dd>\n                    <\/div>\n\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Dyddiad Cychwyn<\/dt>\n                            <dd>\n                                                                    1 <span>Medi<\/span> 2026                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Hyd<\/dt>\n                            <dd>\n                                                                    1 <span>flwyddyn<\/span>                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Dull Astudio<\/dt>\n                            <dd>\n                                                                    Llawn Amser                                                            <\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Lleoliad<\/dt>\n                            <dd><a href=\"#course-options\">Parth Dysgu Blaenau Gwent<\/a><\/dd>\n                        <\/div>\n                    \n                                            <div class=\"course-key-info__col\">\n                            <dt>Lefel<\/dt>\n                            <dd>3<\/dd>\n                        <\/div>\n                                    <\/dl>\n                \n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<section class=\"course-text-content panel-m\">\n    <div class=\"course-text-content__inner inner\">\n        <div class=\"course-text-content__header section-header fade-in\">\n            <div class=\"row justify-content-center\">\n                <div class=\"col-lg-8 col-xl-6\">\n                    <h2 class=\"display-2 text-center\">Yn gryno<\/h2>\n                    <p class=\"lead text-center\">Bydd yr Ysgol Roc Lefel 3, ar y cyd \u00e2 chyfleusterau rhagorol ym Mharth Dysgu Blaenau Gwent, yn cynnig profiad dysgu rhagorol i chi lle gallwch gael y wybodaeth a\u2019r sgiliau penodol sydd eu hangen i gwrdd \u00e2 gofynion y diwydiant cyffrous yma.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"course-text-content__accordions\">\n            <div class=\"row justify-content-center\">\n                <div class=\"col-lg-10 col-xl-8\">\n                    <div class=\"accordion\" id=\"accordionExample\">\n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingOne\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseOne\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseOne\">\n                                        Dyma'r cwrs i chi os...\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseOne\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingOne\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>... Ydych eisiau gyrfa yn y diwydiant cerddoriaeth<br \/> ... Ydych eisiau\u2019r wybodaeth a\u2019r sgiliau ymarferol ar gyfer y diwydiant<br \/> ... Yw eich bryd ar ddilyn cwrs cysylltiedig mewn prifysgol<\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingTwo\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseTwo\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseTwo\">\n                                        Beth fyddaf yn ei wneud?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseTwo\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingTwo\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Mae\u2019r hyblygrwydd a\u2019r ystod o unedau yn cwmpasu amrywiaeth eang o ddisgyblaethau perthnasol. Byddwch yn gallu cael cydnabyddiaeth o\u2019ch cyraeddiadau trwy sgiliau cerddorol ymarferol ar y cyd \u00e2\u2019ch astudiaeth seiliedig-ar-theori.<\/p>\n<p>Blwyddyn 1<\/p>\n<p>Diploma Atodol Lefel 3 RSL ar gyfer Ymarferwyr Cerdd<\/p>\n<ul type=\"disc\">\n<li>Perfformiadau cerddorol byw<\/li>\n<li>Sgiliau ymarfer cerddoriaeth<\/li>\n<li>Y cerddor sesiwn<\/li>\n<li>Dilyniant a chynhyrchu cerddoriaeth<\/li>\n<li>Rheoli digwyddiadau cerddorol<\/li>\n<li>Iechyd a diogelwch mewn digwyddiadau cerddorol<\/li>\n<li>Cyfansoddi<\/li>\n<\/ul>\n<p>Blwyddyn 2<\/p>\n<p>Diploma Estynedig Lefel 3 RSL ar gyfer Ymarferwyr Cerdd<\/p>\n<ul type=\"disc\">\n<li>Recordio sain mewn stiwdio<\/li>\n<li>Peirianneg sain byw<\/li>\n<li>Cynllunio ar gyfer gyrfa mewn cerddoriaeth<\/li>\n<li>Traethawd cerdd estynedig<\/li>\n<li>Perfformio cerddoriaeth wedi\u2019i recordio<\/li>\n<li>Hyrwyddo cerddoriaeth<\/li>\n<li>Datblygiad technoleg recordio cerddoriaeth<\/li>\n<\/ul>\n<p>Er mwyn datblygu eich sgiliau ymarferol, bydd gennych fynediad i stiwdio gyda chyfarpar digidol o\u2019r radd flaenaf. Fe\u2019ch anogir i gymryd rhan mewn digwyddiadau cerddorol niferus trwy gydol y DU.<\/p>\n<p>Byddwch yn cael eich asesu trwy arholiadau, portffolio, gwaith cwrs ac asesiadau ymarferol a byddwch yn cyflawni:<\/p>\n<ul type=\"disc\">\n<li>Diploma Atodol Lefel 3 RSL ar gyfer Ymarferwyr Cerdd (Blwyddyn 1)<\/li>\n<li>Diploma Estynedig Lefel 3 RSL ar gyfer Ymarferwyr Cerdd (Blwyddyn 2)<\/li>\n<li>Bagloriaeth Cymru<\/li>\n<li><a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/our-courses\/skills-development\">Gweithgareddau Sgiliau<\/a><\/li>\n<li><a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/our-courses\/improve-your-maths-and-english\">Mathemateg a Saesneg<\/a><\/li>\n<li>Cymwysterau perthnasol eraill i wella eich set sgiliau<\/li>\n<\/ul>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingThree\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseThree\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseThree\">\n                                        Beth a ddisgwylir ohonof i?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseThree\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingThree\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Bydd angen o leiaf 5 TGAU Gradd C neu uwch arnoch, yn cynnwys naill ai Mathemateg\/Llythrennedd mewn Mathemateg neu Saesneg\/Cymraeg Iaith gyntaf, neu gymhwyster Diploma Lefel 2 gyda Gradd Teilyngdod.<\/p>\n<p>Bydd angen i chi fod \u00e2 diddordeb brwd mewn cerddoriaeth a\u2019r brwdfrydedd a\u2019r penderfyniad i ddatblygu eich sgiliau ymarferol. Mae ymroddiad llwyr i bresenoldeb yn ofynnol, ynghyd \u00e2 pharch at eraill, brwdfrydedd dros y pwnc a hunanysgogiad. Dylech hefyd feddu ar y brwdfrydedd a\u2019r agwedd bositif y bydd darpar gyflogwyr yn chwilio amdanynt.<\/p>\n<p>Disgwylir i chi barhau \u00e2\u2019ch astudiaethau a\u2019ch gwaith cwrs yn eich amser eich hun. Disgwylir i chi hefyd fynychu gymaint o ddigwyddiadau \u00e2 phosibl a rhwydweithio gyda chymaint o bobl ag y gallwch.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingFour\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseFour\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseFour\">\n                                        Beth sy'n digwydd nesaf?\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseFour\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingFour\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Gallech symud ymlaen i gwrs yn ymwneud \u00e2 cherddoriaeth mewn prifysgol neu ddod o hyd i waith mewn meysydd megis sain byw, goleuo, AMP neu Dechnegydd Drymiau neu berfformio ar lefel led-broffesiynol.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingFive\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseFive\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseFive\">\n                                        Gofynion mynediad\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseFive\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingFive\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Byddwch angen o leiaf 5 TGAU gradd C neu uwch, gan gynnwys naill ai Mathemateg neu Gymraeg Iaith Gyntaf\/Saesneg; neu radd Teilyngdod mewn cymhwyster Diploma Lefel 2 priodol.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                                                    <div class=\"accordion-item fade-in\">\n                                <h2 class=\"accordion-header\" id=\"headingSix\">\n                                    <button class=\"accordion-button bg-secondary collapsed\" type=\"button\"\n                                            data-bs-toggle=\"collapse\" data-bs-target=\"#collapseSix\" aria-expanded=\"false\"\n                                            aria-controls=\"collapseSix\">\n                                        Gwybodaeth ychwanegol\n                                    <\/button>\n                                <\/h2>\n                                <div id=\"collapseSix\" class=\"accordion-collapse collapse\" role=\"region\" aria-labelledby=\"headingSix\"\n                                     data-bs-parent=\"#accordionExample\">\n                                    <div class=\"accordion-body\">\n                                        <p>Bydd angen git\u00e2r neu git\u00e2r fas eu hunain ar gitaryddion. Bydd angen gwifren git\u00e2r a ffyn drymio ar bob myfyriwr.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"feature-video bg-secondary\">\n    <div class=\"feature-video__image\">\n        <picture>\n            <source\n                data-sizes=\"100vw\"\n                data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Music-and-Performing-Arts-feature-video-mobile.jpg 860w\"\n                media=\"(max-width: 768px)\"\n            >\n            <source\n                data-sizes=\"100vw\"\n                data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Music-and-Performing-Arts-feature-video-desktop.jpg 1210w,                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Music-and-Performing-Arts-feature-video-desktop.jpg 1519w,                    https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Music-and-Performing-Arts-feature-video-desktop.jpg 3038w\"\n            >\n            <img decoding=\"async\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/Music-and-Performing-Arts-feature-video-desktop.jpg\" alt=\"Music and Performing Arts students\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 3024px; --smush-placeholder-aspect-ratio: 3024\/1400;\">\n        <\/picture>\n    <\/div>\n    <div class=\"feature-video__modal-trigger\">\n        <button type=\"button\" class=\"btn btn-primary btn-play feature-video__button js-btn-play\" data-bs-toggle=\"modal\" data-bs-target=\"#videoModalFeatureVideo3666\">\n            <span class=\"sr-only\">Play Video<\/span>\n            <span class=\"material-symbols-outlined\">play_arrow<\/span>\n        <\/button>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"modal modal-video fade\" id=\"videoModalFeatureVideo3666\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"videoModalFeatureVideoLabel\" aria-hidden=\"true\">\n\n    <div class=\"modal-dialog modal-dialog-centered modal-xl\">\n        <div class=\"modal-content\">\n            <button type=\"button\" class=\"btn-close text-reset\" data-bs-dismiss=\"modal\" aria-label=\"Close\">\n                <span class=\"material-symbols-outlined\">close<\/span>\n            <\/button>\n            <div class=\"modal-body\">\n                <h2 class=\"sr-only\" id=\"videoModalFeatureVideoLabel\">modal video<\/h2>\n\n                <div class=\"ratio ratio-16x9\" data-video-src=\"https:\/\/www.youtube.com\/embed\/T8ceqUjoSM0?list=PLFNeewjoCG8oGfZc_VKHj_VUTwXU2fcXZ&amp;cc_load_policy=0\"><\/div>\n\n            <\/div>\n\n\n                    <\/div>\n    <\/div>\n<\/div>\n\n    <section class=\"course-options panel-p\" id=\"course-options\">\n                <div class=\"course-options__inner inner inner-hide-sm\">\n            <div class=\"course-options__items\">\n                <div class=\"row justify-content-center\">\n                    <div class=\"col-xl-10\">\n                                                    <div class=\"course-card-option fade-in\">\n                                <div class=\"course-card-option__inner\">\n                                    <div class=\"course-card-option__content\">\n                                        <h3 class=\"course-card-option__title h2\">Parth Dysgu Blaenau Gwent<\/h3>\n                                        <dl class=\"course-card-option__details\">\n                                            <div class=\"course-card-option__col\">\n                                                <dt>C\u00f4d y Cwrs<\/dt>\n                                                <dd>EFBE0006AB<\/dd>\n                                            <\/div>\n                                                                                            <div class=\"course-card-option__col\">\n                                                    <dt>Dull Astudio<\/dt>\n                                                    <dd>Llawn Amser<\/dd>\n                                                <\/div>\n                                                                                                                                        <div class=\"course-card-option__col\">\n                                                    <dt>Hyd<\/dt>\n                                                    <dd>1 <span>flwyddyn<\/span><\/dd>\n                                                <\/div>\n                                                                                                                                                                                                                                                                    <\/dl>\n                                                                            <\/div>\n\n                                    <div class=\"course-card-option__buttons\">\n                                        \n                                                                                    <a href=\"https:\/\/enrolment.coleggwent.ac.uk\/Page\/Prospectus_CourseOverview?uio_id=542890&#038;lang=cy\" class=\"btn btn-primary\" target=\"_blank\">\n                                                                                                    <span class=\"apply-day\">1<\/span>\n                                                    <span class=\"apply-month\">Medi <\/span>\n                                                    <span class=\"apply-year\">2026<\/span>\n                                                    <span class=\"apply-separator\">&#8211;<\/span>\n                                                    <span class=\"apply-cta\">Ymgeisiwch nawr<\/span>\n                                                                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                    <div class=\"course-card-option__inner course-card-option__disclaimer inner\">\n                <div class=\"row\">\n                    <div class=\"col-xl-1\"><\/div>\n                    <div class=\"col-xl-10\">\n                        \n                                                    <p>Gall yr holl gyrsiau fod yn agored i newid a\u2019u canslo os tybir nad yw\u2019n bosib eu cynnal.<\/p>\n                                            <\/div>\n                    <div class=\"col-xl-1\"><\/div>\n                <\/div>\n            <\/div>\n            <\/section>\n\n<section class=\"container\">\n    <div class=\"inner\">\n                    <div id=\"pathways-d6b53d\" data-subject=\"automap\" data-callback=\"loadCallback\" data-lang=\"cy\"><\/div>\n            <script src=\"https:\/\/www.career-pathways.co.uk\/assets\/js\/pathways-loader.js\" data-key=\"c8daae74df1eb436ee1072e63d20e706\" async crossorigin=\"anonymous\"><\/script>\n                <script>\n            function loadCallback(iframeId, message) {\n                if (message === 'No automapped subject found') {\n                    iframeId.style.display = 'none';\n                    \n                                    }\n            }\n        <\/script>\n    <\/div>\n<\/section>\n\n\n<section class=\"related-courses panel-m\">\n            <div class=\"related-courses__inner inner\">\n            <h2 class=\"block-title h3 fade-in\">Cyrsiau a all fod at eich dant<\/h2>\n        <\/div>\n        <div class=\"related-courses__inner inner inner-hide-sm\">\n        <div class=\"related-courses__items\">\n            <div class=\"row\">\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-3\">\n                                                Lefel 3                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/be0007\/btec-national-foundation-diploma-in-music-technology-pathway-level-3\" class=\"related-course-card__title h2\">BTEC Diploma Sylfaen Genedlaethol mewn Cerddoriaeth (llwybr Technoleg) Lefel 3<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-3\">\n                                                Lefel 3                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/be0006\/btec-national-foundation-diploma-in-music-level-3\" class=\"related-course-card__title h2\">BTEC Diploma Sylfaen Genedlaethol mewn Cerddoriaeth Lefel 3<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                                                        <div class=\"col-lg-4\">\n                    <div class=\"related-course-card fade-in\">\n                        <div class=\"related-course-card__inner\">\n                            <div class=\"related-course-card__text\">\n                                <ul class=\"tag-list list-unstyled\">\n                                                                            <li>\n                                            <span class=\"tag tag-uppercase accent-yellow\">\n                                                Llawn Amser                                            <\/span>\n                                        <\/li>\n                                    \n                                                                            <li>\n                                            <span class=\"tag tag-uppercase level-2\">\n                                                Lefel 2                                            <\/span>\n                                        <\/li>\n                                                                    <\/ul>\n                                <a href=\"https:\/\/www.coleggwent.ac.uk\/cy\/course\/bd0009\/btec-diploma-in-music-performance-and-technology-level-2\" class=\"related-course-card__title h2\">BTEC Diploma mewn Perfformio Cerddoriaeth a Thechnoleg Lefel 2<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n            <div class=\"related-courses__inner inner\">\n                        <a href=\"\/cy\/course-search\" class=\"btn btn-primary\">Gweld pob cwrs<\/a>\n        <\/div>\n    <\/section>\n\n<section class=\"latest-events position-relative overflow-hidden panel-m\">\n    <div class=\"latest-events__inner inner\">\n        <div class=\"latest-events__header swiper-navigation-header\">\n                            <h2 class=\"block-title h3 fade-in\">Digwyddiadau i ddod<\/h2>\n            \n            <div class=\"latest-events__navigation swiper-navigation swiper-primary\">\n                <button class=\"swiper-button-prev\">\n                    <span class=\"material-symbols-outlined\">chevron_left<\/span>\n                <\/button>\n                <button class=\"swiper-button-next\">\n                    <span class=\"material-symbols-outlined\">chevron_right<\/span>\n                <\/button>\n            <\/div>\n        <\/div>\n        <div class=\"latest-events__items fade-in-cards js-latest-events\">\n            <div class=\"swiper-wrapper\">\n                                                                <div class=\"swiper-slide fade-in\">\n                            <div class=\"card-event accent-yellow\">\n                                <div class=\"card-event__inner\">\n                                                                            <div class=\"card-event__image\">\n\n                                            <img decoding=\"async\" width=\"800\" height=\"600\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb.jpg\" class=\"attachment-full size-full lazyload\" alt=\"Higher Education students walking with tutor\" data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb.jpg 800w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-300x225.jpg 300w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-768x576.jpg 768w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-16x12.jpg 16w, https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/09\/he-event-thumb-373x280.jpg 373w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/600;\" \/>                                        <\/div>\n                                                                        <div class=\"card-event__content\">\n                                                                                    <time class=\"card-event__date display-6\" datetime=\"2026-08-19\">\n                                                <span>\n                                                    Aws                                                <\/span>\n                                                <span>\n                                                    19                                                <\/span>\n                                            <\/time>\n                                                                                <div class=\"card-event__text\">\n                                            <h3 class=\"card-event__title h2\">\n                                                Digwyddiad Agored Addysg Uwch Awst 2026                                            <\/h3>\n                                            <dl class=\"card-event__details\">\n                                                                                                    <div>\n                                                        <dt>Manylion<\/dt>\n                                                        <dd>Cyrsiau addysg uwch<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Lleoliad<\/dt>\n                                                        <dd>Parth Dysgu Blaenau Gwent - Glynebwy<\/dd>\n                                                    <\/div>\n                                                \n                                                                                                    <div>\n                                                        <dt>Amser<\/dt>\n                                                        <dd>2yp - 5yp<\/dd>\n                                                    <\/div>\n                                                                                            <\/dl>\n                                                                                            <a href=\"https:\/\/www.eventbrite.co.uk\/e\/digwyddiad-agored-coleg-gwent-addysg-uwch-tickets-1992480197908\" class=\"btn btn-primary\" aria-label=\"Register for the August 2026 Higher Education Open Event\" target=\"_blank\">\n                                                    Ymgeisiwch nawr                                                <\/a>\n                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"cta-button-group panel-m flip\">\n    <div class=\"cta-button-group__inner inner\">\n        <div class=\"cta-button-group__content bg-pink bg-pattern-accent\">\n            <div class=\"cta-button-group__image shape-2\">\n                                    <picture>\n                        <source\n                            data-sizes=\"100vw\"\n                            data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-music-performance-3.jpg 860w\"\n                            media=\"(max-width: 768px)\"\n                                >\n                        <source\n                            data-sizes=\"(min-width: 1512px) 100vw, 1366px\"\n                            data-srcset=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-music-performance-3.jpg 1366w\"\n                                >\n                        <img decoding=\"async\" data-src=\"https:\/\/www.coleggwent.ac.uk\/wp-content\/uploads\/2025\/07\/cil-music-performance-3.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1185px; --smush-placeholder-aspect-ratio: 1185\/474;\">\n                    <\/picture>\n                            <\/div>\n            <div class=\"cta-button-group__text fade-in\">\n                <div class=\"cta-button-group__title\">\n                    <div class=\"block-text accent-pink\">\n                        <div class=\"block-text__body\">\n                                                            <h2 class=\"display-2\">\n                                    <strong>Oes diddordeb gennych chi?\n<\/strong>\n                                <\/h2>\n                                                                                <\/div>\n                    <\/div>\n                <\/div>\n                <ul class=\"block-list cta-button-group__list-wrapper list-unstyled\">\n                                                                                                                                    <li>\n                                    <a href=\"#course-options\">Ymgeisiwch<\/a>\n                                <\/li>\n                                                                                                                                            <li>\n                                    <a href=\"\/cy\/contact\/?enquiry_type=course_enquiry#form\">Holi<\/a>\n                                <\/li>\n                                                                                                                                            <li>\n                                    <a href=\"mailto:helo@coleggwent.ac.uk\">Cysylltwch \u00e2\u2019n t\u00eem recriwtio myfyrwyr<\/a>\n                                <\/li>\n                                                                                        <\/ul>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":29268,"template":"","subject":[163,151],"course-type":[122],"locations":[115],"sector":[],"promotions":[],"class_list":["post-28516","course","type-course","status-publish","has-post-thumbnail","hentry","course-type-full-time","locations-blaenau-gwent-learning-zone"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","pp_force_visibility":null,"pp_subpost_visibility":null,"pp_inherited_force_visibility":null,"pp_inherited_subpost_visibility":null,"pp_post_mime_type":"","acf":[],"_links":{"self":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":4,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28516\/revisions"}],"predecessor-version":[{"id":33746,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course\/28516\/revisions\/33746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/media\/29268"}],"wp:attachment":[{"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/media?parent=28516"}],"wp:term":[{"taxonomy":"subject","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/subject?post=28516"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/course-type?post=28516"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/locations?post=28516"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/sector?post=28516"},{"taxonomy":"promotions","embeddable":true,"href":"https:\/\/www.coleggwent.ac.uk\/cy\/wp-json\/wp\/v2\/promotions?post=28516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}